{"id":11554,"date":"2021-07-05T15:22:24","date_gmt":"2021-07-05T13:22:24","guid":{"rendered":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/"},"modified":"2021-07-05T16:47:20","modified_gmt":"2021-07-05T14:47:20","slug":"altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants","status":"publish","type":"post","link":"https:\/\/altea-energy.com\/pt-pt\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/","title":{"rendered":"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A Altea Energy, especializada h\u00e1 10 anos na presta\u00e7\u00e3o de consultores aut\u00f4nomos para o setor de energia (petr\u00f3leo, g\u00e1s, renov\u00e1veis), recruta e mobiliza os melhores especialistas para os projetos de seus clientes, grandes players de energia.<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18pt;\"><strong>Altea Energy ao servi\u00e7o da transi\u00e7\u00e3o energ\u00e9tica<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">A transi\u00e7\u00e3o energ\u00e9tica \u00e9 um desafio significativo para os principais grupos de energia. A Altea Energy agora ap\u00f3ia os jogadores neste setor, fornecendo especialistas t\u00e9cnicos que lhes permitem realizar seus projetos de energia verde com tranquilidade. Tem por objetivo: encontrar as compet\u00eancias, selecionar o melhor consultor para o projeto, gerir a sua contrata\u00e7\u00e3o, mobiliz\u00e1-lo para o local de opera\u00e7\u00e3o, zelar pelo seu cumprimento junto das autoridades locais e garantir o pagamento do consultor ap\u00f3s cada rota\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Os projetos dos clientes da Altea Energy acontecem principalmente na Europa, \u00c1frica e Oriente M\u00e9dio e t\u00eam diversos objetivos. J\u00e1 envolvidos na transi\u00e7\u00e3o energ\u00e9tica ou no processo de transi\u00e7\u00e3o, todos os seus clientes precisam de especialistas para apoiar essa transforma\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>As empresas de energia j\u00e1 ativas em energias renov\u00e1veis geralmente enfrentam problemas de crescimento: elas crescem rapidamente e n\u00e3o t\u00eam tempo para recrutar recursos internos suficientes para poder entregar seus projetos. \u00c9 por isso que respondemos \u00e0s suas necessidades, disponibilizando-lhes consultores aut\u00f4nomos imediatamente dispon\u00edveis, com os conhecimentos t\u00e9cnicos necess\u00e1rios, que podem ser destacados em car\u00e1ter emergencial nos pa\u00edses em que atuam. Executamos o servi\u00e7o de A a Z para que nossos clientes possam focar no que mais importa: o sucesso de seus projetos.<\/em>&#8221; explica Nicolas Kotliar, cofundador da Altea Energy.<\/p>\n<p style=\"text-align: justify;\">Da mesma forma, as empresas especializadas em combust\u00edveis f\u00f3sseis que desejam fazer a transi\u00e7\u00e3o para as energias renov\u00e1veis devem enfrentar grandes mudan\u00e7as. Esses atores n\u00e3o t\u00eam necessariamente as habilidades necess\u00e1rias internamente para conseguir isso. Os processos de recrutamento levam tempo, ent\u00e3o eles recorrem a consultores externos qualificados para ajud\u00e1-los a pensar em sua estrat\u00e9gia de transi\u00e7\u00e3o energ\u00e9tica e realizar seus projetos de energia verde.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18pt;\"><strong>Digitaliza\u00e7\u00e3o acelerada de servi\u00e7os<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">O setor de energia enfrenta um atraso em termos de digitaliza\u00e7\u00e3o. A Altea Energy deseja assim posicionar-se como um parceiro na oferta de servi\u00e7os digitais inovadores, que proporcionem aos seus clientes mais transpar\u00eancia e agilidade na gest\u00e3o dos consultores.<\/p>\n<p style=\"text-align: justify;\">Nicolas Kotliar explica: \u201c<em>O COVID-19 acelerou a digitaliza\u00e7\u00e3o do setor. Perante os constrangimentos ligados \u00e0 pandemia, devemos facilitar a vida dos nossos clientes e permitir-lhes poupar tempo gra\u00e7as \u00e0 tecnologia digital (assinatura eletr\u00f3nica, apresenta\u00e7\u00e3o eletr\u00f3nica de faturas, etc.). Quanto aos nossos consultores, \u00e9 importante que possam ter todas as informa\u00e7\u00f5es sobre as suas atribui\u00e7\u00f5es em tempo real atrav\u00e9s de um portal seguro: contrato de trabalho, vistos, passagem a\u00e9rea, reserva de hotel, contactos de emerg\u00eancia, quadro de hor\u00e1rios e despesas, pagamentos &#8230;<\/em> \u201d<\/p>\n<p style=\"text-align: justify;\">H\u00e1 mais de dois anos, a empresa investe fortemente em tecnologias digitais. O processo de digitaliza\u00e7\u00e3o foi iniciado internamente com o objetivo de aumentar a efici\u00eancia, proporcionando assim melhor qualidade de servi\u00e7o aos clientes e maior capacidade de resposta \u00e0s necessidades dos seus consultores aut\u00f4nomos. Com a chegada do COVID-19 e os constrangimentos implicados pela crise, a empresa teve de acelerar a digitaliza\u00e7\u00e3o externa. Para isso, as equipas trabalharam em produtos digitais para disponibilizar tanto a clientes como a consultores, de forma a reduzir as interac\u00e7\u00f5es que habitualmente requerem a presen\u00e7a.<\/p>\n<p style=\"text-align: justify;\"><em>\u201cDiante dessa acelera\u00e7\u00e3o da digitaliza\u00e7\u00e3o, trabalhamos diariamente para garantir que todas as ferramentas e processos de trabalho estejam bem estruturados e funcionais. A tecnologia digital permite-nos ser mais eficientes, ao mesmo tempo que proporciona mais transpar\u00eancia e flexibilidade aos nossos clientes<\/em>\u201d, conclui Nicolas Kotliar.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 18pt;\"><strong>\u00abFreelancization\u00bb para benef\u00edcio dos jogadores de energia<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">No setor de energia, cada vez mais especialistas s\u00e3o aut\u00f4nomos, o que vai de par com os desafios encontrados neste setor. Na verdade, a necessidade de conhecimento t\u00e9cnico \u00e9 sentida em projetos complexos. Para atender \u00e0s necessidades desses projetos, nem sempre s\u00e3o necess\u00e1rios especialistas qualificados e mobiliza\u00e7\u00f5es r\u00e1pidas, o que nem sempre \u00e9 compat\u00edvel com os processos de recrutamento interno.<\/p>\n<p style=\"text-align: justify;\">Nicolas Kotliar e Pamela Bobillier, Diretora da Transforma\u00e7\u00e3o, explicam: \u201c<em>A m\u00e3o de obra no setor de energia tem cada vez mais consultores independentes. Isso est\u00e1 relacionado ao fato de que o nosso neg\u00f3cio \u00e9 muito c\u00edclico, pois depende principalmente dos pre\u00e7os das mat\u00e9rias-primas. A necessidade de pessoal nos projetos \u00e9, portanto, muito flutuante. Por outro lado, existe o desejo dos especialistas de maior flexibilidade em seu modelo de trabalho. Para agilizar e entregar melhor, contamos, portanto, com especialistas independentes. Hoje, existem muitos freelances no mercado que fizeram carreira em grandes empresas e que querem usufruir de um sistema mais flex\u00edvel, que lhes permita escolher as suas atribui\u00e7\u00f5es e os pa\u00edses onde v\u00e3o trabalhar.<\/em>\u201d<\/p>\n<p style=\"text-align: justify;\">Nicolas Kotliar conclui: \u201c<em>A pr\u00e9-lamina\u00e7\u00e3o de recursos \u00e9 uma tend\u00eancia geral no mercado de trabalho muito acelerada pela pandemia. Esta tend\u00eancia ganha todo o seu sentido num setor como o nosso, que exige grande compet\u00eancia t\u00e9cnica e muita flexibilidade. Estamos muito satisfeitos por poder contribuir para isso h\u00e1 mais de 10 anos.<\/em>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"A Altea Energy, especializada h\u00e1 10 anos na presta\u00e7\u00e3o de consultores aut\u00f4nomos para o setor de energia (petr\u00f3leo, g\u00e1s, renov\u00e1veis), recruta e mobiliza os melhores especialistas para os projetos de seus clientes, grandes players de energia. Altea Energy ao servi\u00e7o da transi\u00e7\u00e3o energ\u00e9tica A transi\u00e7\u00e3o energ\u00e9tica \u00e9 um desafio significativo para os principais grupos de [&hellip;]","protected":false},"author":6,"featured_media":11544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[494,17],"tags":[],"class_list":["post-11554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clients-fr","category-corporate"],"acf":{"post_in_portal":true,"post_hide_banner":false,"post_image":11544,"post_tags":false,"post_excerpt":"<p>Nicolas Kotliar, nosso cofundador e Diretor Geral, explica no site da <em>Challenges<\/em> como a Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as ao fornecimento de consultores t\u00e9cnicos aut\u00f4nomos e \u00e0 digitaliza\u00e7\u00e3o de servi\u00e7os para clientes e consultores. Descubra mais no artigo original em <a href=\"https:\/\/www.challenges.fr\/economie\/altea-energy-soutient-la-transition-energetique_772090?utm_source=linkedin&amp;utm_medium=linkedin&amp;utm_campaign=challenges.fr\">Challenges.fr<\/a>.<\/p>"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos - Altea Energy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/altea-energy.com\/pt-pt\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos - Altea Energy\" \/>\n<meta property=\"og:description\" content=\"A Altea Energy, especializada h\u00e1 10 anos na presta\u00e7\u00e3o de consultores aut\u00f4nomos para o setor de energia (petr\u00f3leo, g\u00e1s, renov\u00e1veis), recruta e mobiliza os melhores especialistas para os projetos de seus clientes, grandes players de energia. Altea Energy ao servi\u00e7o da transi\u00e7\u00e3o energ\u00e9tica A transi\u00e7\u00e3o energ\u00e9tica \u00e9 um desafio significativo para os principais grupos de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt\" \/>\n<meta property=\"og:site_name\" content=\"Altea Energy\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-05T13:22:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-05T14:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1158\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pamela Bobillier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pamela Bobillier\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt\"},\"author\":{\"name\":\"Pamela Bobillier\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/person\\\/031cd93834bf64446001ff5963398af6\"},\"headline\":\"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos\",\"datePublished\":\"2021-07-05T13:22:24+00:00\",\"dateModified\":\"2021-07-05T14:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt\"},\"wordCount\":909,\"publisher\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/Capture-decran-1495.png\",\"articleSection\":[\"Clients\",\"Corporate\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt\",\"name\":\"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos - Altea Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/Capture-decran-1495.png\",\"datePublished\":\"2021-07-05T13:22:24+00:00\",\"dateModified\":\"2021-07-05T14:47:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#primaryimage\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/Capture-decran-1495.png\",\"contentUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/Capture-decran-1495.png\",\"width\":1158,\"height\":815},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\\\/?lang=pt-pt#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/altea-energy.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#website\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/\",\"name\":\"Altea Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/altea-energy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#organization\",\"name\":\"Altea Energy\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/logo-altea.svg\",\"contentUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/logo-altea.svg\",\"width\":1,\"height\":1,\"caption\":\"Altea Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/altea-resources\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/person\\\/031cd93834bf64446001ff5963398af6\",\"name\":\"Pamela Bobillier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d203a19e2c5e515ab14bffa882bcebe98291173bc977e01592d655d7dfeaa28f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d203a19e2c5e515ab14bffa882bcebe98291173bc977e01592d655d7dfeaa28f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d203a19e2c5e515ab14bffa882bcebe98291173bc977e01592d655d7dfeaa28f?s=96&d=mm&r=g\",\"caption\":\"Pamela Bobillier\"},\"url\":\"https:\\\/\\\/altea-energy.com\\\/pt-pt\\\/author\\\/admin_altears\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos - Altea Energy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/altea-energy.com\/pt-pt\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt","og_locale":"pt_PT","og_type":"article","og_title":"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos - Altea Energy","og_description":"A Altea Energy, especializada h\u00e1 10 anos na presta\u00e7\u00e3o de consultores aut\u00f4nomos para o setor de energia (petr\u00f3leo, g\u00e1s, renov\u00e1veis), recruta e mobiliza os melhores especialistas para os projetos de seus clientes, grandes players de energia. Altea Energy ao servi\u00e7o da transi\u00e7\u00e3o energ\u00e9tica A transi\u00e7\u00e3o energ\u00e9tica \u00e9 um desafio significativo para os principais grupos de [&hellip;]","og_url":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt","og_site_name":"Altea Energy","article_published_time":"2021-07-05T13:22:24+00:00","article_modified_time":"2021-07-05T14:47:20+00:00","og_image":[{"width":1158,"height":815,"url":"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png","type":"image\/png"}],"author":"Pamela Bobillier","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pamela Bobillier","Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#article","isPartOf":{"@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt"},"author":{"name":"Pamela Bobillier","@id":"https:\/\/altea-energy.com\/#\/schema\/person\/031cd93834bf64446001ff5963398af6"},"headline":"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos","datePublished":"2021-07-05T13:22:24+00:00","dateModified":"2021-07-05T14:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt"},"wordCount":909,"publisher":{"@id":"https:\/\/altea-energy.com\/#organization"},"image":{"@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#primaryimage"},"thumbnailUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png","articleSection":["Clients","Corporate"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt","url":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt","name":"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos - Altea Energy","isPartOf":{"@id":"https:\/\/altea-energy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#primaryimage"},"image":{"@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#primaryimage"},"thumbnailUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png","datePublished":"2021-07-05T13:22:24+00:00","dateModified":"2021-07-05T14:47:20+00:00","breadcrumb":{"@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#primaryimage","url":"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png","contentUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png","width":1158,"height":815},{"@type":"BreadcrumbList","@id":"https:\/\/altea-energy.com\/altea-energy-supports-the-energy-transition-of-its-clients-thanks-to-freelance-consultants\/?lang=pt-pt#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/altea-energy.com\/home\/"},{"@type":"ListItem","position":2,"name":"A Altea Energy ap\u00f3ia a transi\u00e7\u00e3o energ\u00e9tica de seus clientes gra\u00e7as a consultores aut\u00f4nomos"}]},{"@type":"WebSite","@id":"https:\/\/altea-energy.com\/#website","url":"https:\/\/altea-energy.com\/","name":"Altea Energy","description":"","publisher":{"@id":"https:\/\/altea-energy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/altea-energy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/altea-energy.com\/#organization","name":"Altea Energy","url":"https:\/\/altea-energy.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/altea-energy.com\/#\/schema\/logo\/image\/","url":"https:\/\/altea-energy.com\/wp-content\/uploads\/logo-altea.svg","contentUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/logo-altea.svg","width":1,"height":1,"caption":"Altea Energy"},"image":{"@id":"https:\/\/altea-energy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/altea-resources\/"]},{"@type":"Person","@id":"https:\/\/altea-energy.com\/#\/schema\/person\/031cd93834bf64446001ff5963398af6","name":"Pamela Bobillier","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/d203a19e2c5e515ab14bffa882bcebe98291173bc977e01592d655d7dfeaa28f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d203a19e2c5e515ab14bffa882bcebe98291173bc977e01592d655d7dfeaa28f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d203a19e2c5e515ab14bffa882bcebe98291173bc977e01592d655d7dfeaa28f?s=96&d=mm&r=g","caption":"Pamela Bobillier"},"url":"https:\/\/altea-energy.com\/pt-pt\/author\/admin_altears\/"}]}},"jetpack_featured_media_url":"https:\/\/altea-energy.com\/wp-content\/uploads\/Capture-decran-1495.png","lang":"pt-pt","_links":{"self":[{"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/posts\/11554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=11554"}],"version-history":[{"count":0,"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/posts\/11554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/media\/11544"}],"wp:attachment":[{"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=11554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=11554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altea-energy.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=11554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}