{"id":22528,"date":"2026-03-03T09:54:34","date_gmt":"2026-03-03T08:54:34","guid":{"rendered":"https:\/\/altea-energy.com\/?p=22528"},"modified":"2026-03-03T13:04:14","modified_gmt":"2026-03-03T12:04:14","slug":"10-ans-engagement-altea-energy-parcours-eva-berton","status":"publish","type":"post","link":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/","title":{"rendered":"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton"},"content":{"rendered":"<h3>Un parcours construit au c\u0153ur des op\u00e9rations<\/h3>\n<p>Eva Berton rejoint Altea Energy il y a dix ans comme Senior Recruitment Consultant, apr\u00e8s une premi\u00e8re exp\u00e9rience dans le secteur Oil &amp; Gas. Tr\u00e8s vite, elle se distingue par sa compr\u00e9hension fine des enjeux humains et op\u00e9rationnels du recrutement.<\/p>\n<p><em>\u00ab J\u2019ai toujours \u00e9t\u00e9 passionn\u00e9e par le cycle complet du recrutement : trouver le bon match, accompagner les talents dans leur d\u00e9veloppement et cr\u00e9er des relations durables bas\u00e9es sur la confiance. \u00bb<\/em>, explique <strong>Eva Berton<\/strong>.<\/p>\n<p>Au fil des ann\u00e9es, elle \u00e9volue vers le poste de Head of Recruitment, o\u00f9 elle structure les \u00e9quipes, d\u00e9veloppe des processus scalables et renforce la performance collective.<\/p>\n<p>Cette exp\u00e9rience manag\u00e9riale lui apporte une compr\u00e9hension transversale du mod\u00e8le Altea Energy, qui constitue aujourd\u2019hui un v\u00e9ritable atout dans le nouveau r\u00f4le qui lui a \u00e9t\u00e9 confi\u00e9.<\/p>\n<p><em>\u00ab En tant que Head of Recruitment, j\u2019ai pu comprendre combien la culture humaine, la structure et le leadership peuvent influencer positivement les r\u00e9sultats, la motivation des \u00e9quipes et l\u2019exp\u00e9rience d\u00e9livr\u00e9e au client. \u00bb<\/em>, <strong>ajoute-t-elle<\/strong>.<\/p>\n<h3>La cr\u00e9ation d\u2019un poste de Chief Revenue Officer pour anticiper les besoins et cr\u00e9er de la valeur pour les clients<\/h3>\n<p>Nomm\u00e9e r\u00e9cemment Chief Revenue Officer d\u2019Altea Energy, Eva prend un r\u00f4le strat\u00e9gique qui s\u2019inscrit dans la continuit\u00e9 de son parcours : relier l\u2019op\u00e9rationnel et la vision long terme.<\/p>\n<p><em>\u201cEva incarne la culture Altea Energy : engagement, vision et leadership construit dans la dur\u00e9e. Sa nomination refl\u00e8te notre volont\u00e9 de promouvoir les talents qui ont grandi avec l\u2019entreprise et contribu\u00e9 \u00e0 son d\u00e9veloppement.\u201d<\/em>, souligne <strong>Nicolas Kotliar, Cofondateur et Directeur G\u00e9n\u00e9ral d\u2019Altea Energy<\/strong>.<\/p>\n<p>A ce nouveau poste, ses missions seront de :<\/p>\n<ul>\n<li>Piloter la strat\u00e9gie de croissance du groupe et son d\u00e9veloppement commercial,<\/li>\n<li>Construire une strat\u00e9gie de partenariats long terme avec les clients et identifier de nouvelles opportunit\u00e9s,<\/li>\n<li>Structurer l\u2019excellence op\u00e9rationnelle afin d\u2019am\u00e9liorer en permanence l\u2019exp\u00e9rience client et renforcer la proximit\u00e9.<\/li>\n<\/ul>\n<p><em>\u00ab Forte de mes dix ann\u00e9es d\u2019exp\u00e9riences terrain et manag\u00e9riale, je comprends la r\u00e9alit\u00e9 op\u00e9rationnelle derri\u00e8re chaque projet, \u00e0 la crois\u00e9e des enjeux de nos clients et des attentes de nos consultants, ainsi que la n\u00e9cessit\u00e9 d\u2019impliquer nos \u00e9quipes sales et op\u00e9rationnelles \u00e0 chaque \u00e9tape.<\/em><\/p>\n<p><em>Cette vision \u00e0 360\u00b0 me permettra de continuer \u00e0 d\u00e9velopper des relations partenariales solides, de construire un pont entre leurs besoins actuels de nos clients et les solutions que nous devons cr\u00e9er pour demain, et ainsi de structurer nos prochaines \u00e9tapes de croissance. \u00bb<\/em>, <strong>pr\u00e9cise Eva<\/strong>.<\/p>\n<h3>Plus que l\u2019expertise technique : l\u2019humain, l\u2019atout c\u0153ur d\u2019Altea Energy<\/h3>\n<p><em>\u00ab Je me souviens que lors de mon entretien d\u2019embauche, j\u2019avais demand\u00e9 : <strong>\u00ab Et moi, pourquoi je devrais rejoindre l\u2019\u00e9quipe Altea Energy ? \u00bb<\/strong>.<\/em><\/p>\n<p><em>Les r\u00e9ponses que j\u2019ai entendues \u00e0 l\u2019\u00e9poque sont les m\u00eames que je pourrais partager aujourd\u2019hui : une \u00e9quipe incroyable, un environnement international, un fort esprit d\u2019\u00e9quipe et beaucoup d\u2019opportunit\u00e9s d\u2019apprendre et de grandir.<\/em><\/p>\n<p><em>Lorsque je repense \u00e0 ces dix ann\u00e9es chez Altea Energy, ma plus grande fiert\u00e9 n\u2019est pas li\u00e9e \u00e0 un titre ou \u00e0 une \u00e9tape cl\u00e9.<\/em><\/p>\n<p><em>Ce sont les personnes et les relations construites.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"325\" class=\"alignnone size-full wp-image-22542\" src=\"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-corporate-values-team-building-1-blog.jpg\" alt=\"\" \/><\/p>\n<p><em>J\u2019ai vu l\u2019\u00e9quipe grandir.<\/em><br \/>\n<em>Le p\u00e9rim\u00e8tre d\u2019intervention s\u2019\u00e9largir.<\/em><br \/>\n<em>La communaut\u00e9 de consultants se d\u00e9velopper.<\/em><br \/>\n<em>Les process internes se structurer.<\/em><br \/>\n<em>Les projets \u00e9nerg\u00e9tiques accompagn\u00e9s devenir plus complexes.<\/em><\/p>\n<p><em>L\u2019entreprise a franchi des caps importants, tout en restant fid\u00e8le \u00e0 son ADN. Elle n\u2019a perdu ni son agilit\u00e9, ni son esprit profond\u00e9ment humain.<\/em><\/p>\n<p><em>Il n\u2019y a pas un moment unique marquant dans mon parcours, mais plut\u00f4t un sentiment que j\u2019ai ressenti \u00e0 de nombreuses reprises : la gratitude d\u2019un consultant dont la carri\u00e8re a pris un nouveau tournant avec nous, un coll\u00e8gue qui \u00e9volue vers la meilleure version de lui-m\u00eame, un client qui nous dit se sentir v\u00e9ritablement accompagn\u00e9 et travailler avec nous autant pour notre expertise que pour la mani\u00e8re dont nous nous comportons avec nos \u00e9quipes et nos consultants.<\/em><\/p>\n<p><em>\u00c0 chaque fois que j\u2019entends cela, je me rappelle pourquoi j\u2019ai rejoint l\u2019entreprise, pourquoi j\u2019y suis rest\u00e9e et pourquoi je suis fi\u00e8re de notre parcours.<\/em><\/p>\n<p><em>Parce que cela refl\u00e8te notre culture : une entreprise o\u00f9 les personnes comptent, o\u00f9 la confiance se construit et o\u00f9 les relations passent avant tout.<\/em><\/p>\n<p><em>Si nous prenons soin de nos \u00e9quipes, elles prennent soin de nos clients et les r\u00e9sultats suivent.<\/em><\/p>\n<p><em>C\u2019est cette valeur humaine, au-del\u00e0 de notre expertise technique et des d\u00e9fis relev\u00e9s avec nos clients, que j\u2019ai l\u2019envie de continuer \u00e0 d\u00e9velopper et d\u2019incarner dans nos prochaines \u00e9tapes de croissance. \u00bb<\/em>, <strong>conclut Eva Berton<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"325\" class=\"alignnone size-full wp-image-22545\" src=\"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-corporate-values-team-building-2-blog.jpg\" alt=\"\" \/><\/p>\n<p>\u2014\u2014\u2014\u2013<\/p>\n<h3>A propos d\u2019Altea Energy<\/h3>\n<h4><strong>Rejoignez notre communaut\u00e9 d\u2019experts et ensemble, transformons les \u00e9nergies de demain !<\/strong><\/h4>\n<p>Depuis 2008, Altea Energy accompagne l\u2019industrie mondiale de l\u2019\u00e9nergie, et a s\u00e9lectionn\u00e9 et mobilis\u00e9 des milliers de consultants, sur plus de 300 projets ambitieux dans les secteurs du p\u00e9trole et du gaz, du nucl\u00e9aire et des \u00e9nergies renouvelables.<\/p>\n<p>Entreprise internationale dont le si\u00e8ge est bas\u00e9 en France, le Groupe s\u2019appuie sur 12 bureaux \u00e0 l\u2019international et des \u00e9quipes locales. Nous mobilisons les consultants dans plus de 100 pays, avec une forte empreinte en Afrique, en Europe, au Moyen-Orient, et en Am\u00e9rique du Sud, en pleine conformit\u00e9 avec les lois et les r\u00e9glementations locales.<\/p>\n<p>Avec l\u2019acquisition de TEAM Energy en 2025, sp\u00e9cialiste britannique de l\u2019assistance technique et du support \u00e0 l\u2019ing\u00e9nierie depuis 1987, Altea Energy renforce sa pr\u00e9sence en Europe, au Moyen Orient et en Asie, et \u00e9largit encore son champ d\u2019expertises.<\/p>\n","protected":false},"excerpt":{"rendered":"Un parcours construit au c\u0153ur des op\u00e9rations Eva Berton rejoint Altea Energy il y a dix ans comme Senior Recruitment Consultant, apr\u00e8s une premi\u00e8re exp\u00e9rience dans le secteur Oil &amp; Gas. Tr\u00e8s vite, elle se distingue par sa compr\u00e9hension fine des enjeux humains et op\u00e9rationnels du recrutement. \u00ab J\u2019ai toujours \u00e9t\u00e9 passionn\u00e9e par le cycle [&hellip;]","protected":false},"author":8,"featured_media":22537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[496,494,498],"tags":[],"class_list":["post-22528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consultants-fr","category-clients-fr","category-corporate-fr"],"acf":{"post_in_portal":true,"post_hide_banner":false,"post_image":22537,"post_tags":false,"post_excerpt":"<div class=\"flex-shrink-0 flex flex-col relative items-end\">\r\n<div class=\"pt-0\">\r\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\r\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\">\r\n\r\nCette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e.\r\n\r\nUne \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton - Altea Energy<\/title>\n<meta name=\"description\" content=\"Cette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e. Une \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton - Altea Energy\" \/>\n<meta property=\"og:description\" content=\"Cette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e. Une \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/\" \/>\n<meta property=\"og:site_name\" content=\"Altea Energy\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-03T08:54:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T12:04:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"866\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ga\u00eblle Dendeleux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ga\u00eblle Dendeleux\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/\"},\"author\":{\"name\":\"Ga\u00eblle Dendeleux\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/person\\\/07ed619c7d0b036dd26d97ae8944ed36\"},\"headline\":\"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton\",\"datePublished\":\"2026-03-03T08:54:34+00:00\",\"dateModified\":\"2026-03-03T12:04:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/\"},\"wordCount\":993,\"publisher\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/altea-energy-eva-berton-cro-corporate-values-blog.jpg\",\"articleSection\":[\"Consultants\",\"Clients\",\"Corporate\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/\",\"name\":\"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton - Altea Energy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/altea-energy-eva-berton-cro-corporate-values-blog.jpg\",\"datePublished\":\"2026-03-03T08:54:34+00:00\",\"dateModified\":\"2026-03-03T12:04:14+00:00\",\"description\":\"Cette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e. Une \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/altea-energy-eva-berton-cro-corporate-values-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/altea-energy-eva-berton-cro-corporate-values-blog.jpg\",\"width\":1200,\"height\":866},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/10-ans-engagement-altea-energy-parcours-eva-berton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#website\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/\",\"name\":\"Altea Energy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/altea-energy.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#organization\",\"name\":\"Altea Energy\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/logo-altea.svg\",\"contentUrl\":\"https:\\\/\\\/altea-energy.com\\\/wp-content\\\/uploads\\\/logo-altea.svg\",\"width\":1,\"height\":1,\"caption\":\"Altea Energy\"},\"image\":{\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/altea-resources\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/altea-energy.com\\\/#\\\/schema\\\/person\\\/07ed619c7d0b036dd26d97ae8944ed36\",\"name\":\"Ga\u00eblle Dendeleux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e01e18955b6737ad1b751acf1585dbc34a45ca28590468d018c2451942489aa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e01e18955b6737ad1b751acf1585dbc34a45ca28590468d018c2451942489aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e01e18955b6737ad1b751acf1585dbc34a45ca28590468d018c2451942489aa?s=96&d=mm&r=g\",\"caption\":\"Ga\u00eblle Dendeleux\"},\"url\":\"https:\\\/\\\/altea-energy.com\\\/fr\\\/author\\\/admin_gaelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton - Altea Energy","description":"Cette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e. Une \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/","og_locale":"fr_FR","og_type":"article","og_title":"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton - Altea Energy","og_description":"Cette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e. Une \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.","og_url":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/","og_site_name":"Altea Energy","article_published_time":"2026-03-03T08:54:34+00:00","article_modified_time":"2026-03-03T12:04:14+00:00","og_image":[{"width":1200,"height":866,"url":"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg","type":"image\/jpeg"}],"author":"Ga\u00eblle Dendeleux","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Ga\u00eblle Dendeleux","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#article","isPartOf":{"@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/"},"author":{"name":"Ga\u00eblle Dendeleux","@id":"https:\/\/altea-energy.com\/#\/schema\/person\/07ed619c7d0b036dd26d97ae8944ed36"},"headline":"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton","datePublished":"2026-03-03T08:54:34+00:00","dateModified":"2026-03-03T12:04:14+00:00","mainEntityOfPage":{"@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/"},"wordCount":993,"publisher":{"@id":"https:\/\/altea-energy.com\/#organization"},"image":{"@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#primaryimage"},"thumbnailUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg","articleSection":["Consultants","Clients","Corporate"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/","url":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/","name":"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton - Altea Energy","isPartOf":{"@id":"https:\/\/altea-energy.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#primaryimage"},"image":{"@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#primaryimage"},"thumbnailUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg","datePublished":"2026-03-03T08:54:34+00:00","dateModified":"2026-03-03T12:04:14+00:00","description":"Cette ann\u00e9e, Eva Berton c\u00e9l\u00e8bre ses 10 ans chez Altea Energy. D\u2019abord Senior Recruitment Consultant, puis Head of Recruitment, et d\u00e9sormais Chief Revenue Officer, elle incarne un parcours construit dans la dur\u00e9e. Une \u00e9volution qui illustre avant tout la culture de l\u2019entreprise : faire grandir ses talents en interne et construire un leadership fond\u00e9 sur l\u2019exp\u00e9rience terrain. Retour sur le parcours inspirant d\u2019Eva et sa vision de la culture d\u2019Altea Energy.","breadcrumb":{"@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#primaryimage","url":"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg","contentUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg","width":1200,"height":866},{"@type":"BreadcrumbList","@id":"https:\/\/altea-energy.com\/fr\/10-ans-engagement-altea-energy-parcours-eva-berton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/altea-energy.com\/fr\/"},{"@type":"ListItem","position":2,"name":"10 ans d\u2019engagement chez Altea Energy : le parcours d\u2019Eva Berton"}]},{"@type":"WebSite","@id":"https:\/\/altea-energy.com\/#website","url":"https:\/\/altea-energy.com\/","name":"Altea Energy","description":"","publisher":{"@id":"https:\/\/altea-energy.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/altea-energy.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/altea-energy.com\/#organization","name":"Altea Energy","url":"https:\/\/altea-energy.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/altea-energy.com\/#\/schema\/logo\/image\/","url":"https:\/\/altea-energy.com\/wp-content\/uploads\/logo-altea.svg","contentUrl":"https:\/\/altea-energy.com\/wp-content\/uploads\/logo-altea.svg","width":1,"height":1,"caption":"Altea Energy"},"image":{"@id":"https:\/\/altea-energy.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/altea-resources\/"]},{"@type":"Person","@id":"https:\/\/altea-energy.com\/#\/schema\/person\/07ed619c7d0b036dd26d97ae8944ed36","name":"Ga\u00eblle Dendeleux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/6e01e18955b6737ad1b751acf1585dbc34a45ca28590468d018c2451942489aa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e01e18955b6737ad1b751acf1585dbc34a45ca28590468d018c2451942489aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e01e18955b6737ad1b751acf1585dbc34a45ca28590468d018c2451942489aa?s=96&d=mm&r=g","caption":"Ga\u00eblle Dendeleux"},"url":"https:\/\/altea-energy.com\/fr\/author\/admin_gaelle\/"}]}},"jetpack_featured_media_url":"https:\/\/altea-energy.com\/wp-content\/uploads\/altea-energy-eva-berton-cro-corporate-values-blog.jpg","lang":"fr","_links":{"self":[{"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/posts\/22528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/comments?post=22528"}],"version-history":[{"count":2,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/posts\/22528\/revisions"}],"predecessor-version":[{"id":22557,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/posts\/22528\/revisions\/22557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/media\/22537"}],"wp:attachment":[{"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/media?parent=22528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/categories?post=22528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/altea-energy.com\/fr\/wp-json\/wp\/v2\/tags?post=22528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}